{"id":5854,"date":"2026-05-02T10:23:07","date_gmt":"2026-05-02T09:23:07","guid":{"rendered":"https:\/\/ciarbnigeria.org\/conference\/associate\/eferoghene-cherish-hunder\/"},"modified":"2026-05-02T10:23:07","modified_gmt":"2026-05-02T09:23:07","slug":"eferoghene-cherish-hunder","status":"publish","type":"associate","link":"https:\/\/ciarbnigeria.org\/conference\/associate\/eferoghene-cherish-hunder\/","title":{"rendered":"Eferoghene Cherish Hunder"},"content":{"rendered":"<p>hunderefe@gmail.com<\/p>\n","protected":false},"parent":0,"menu_order":0,"template":"","meta":{"nf_dc_page":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"class_list":["post-5854","associate","type-associate","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eferoghene Cherish Hunder - CIARB Conference<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciarbnigeria.org\/conference\/associate\/eferoghene-cherish-hunder\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eferoghene Cherish Hunder - CIARB Conference\" \/>\n<meta property=\"og:description\" content=\"hunderefe@gmail.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciarbnigeria.org\/conference\/associate\/eferoghene-cherish-hunder\/\" \/>\n<meta property=\"og:site_name\" content=\"CIARB Conference\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/associate\\\/eferoghene-cherish-hunder\\\/\",\"url\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/associate\\\/eferoghene-cherish-hunder\\\/\",\"name\":\"Eferoghene Cherish Hunder - CIARB Conference\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/#website\"},\"datePublished\":\"2026-05-02T09:23:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/associate\\\/eferoghene-cherish-hunder\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/associate\\\/eferoghene-cherish-hunder\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/associate\\\/eferoghene-cherish-hunder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Associates\",\"item\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/associate\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eferoghene Cherish Hunder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/#website\",\"url\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/\",\"name\":\"CIARB Conference\",\"description\":\"Annual Conference\",\"publisher\":{\"@id\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/#organization\",\"name\":\"CIARB Conference\",\"url\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cropped-2026-Conference-logo-Transparent.png\",\"contentUrl\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cropped-2026-Conference-logo-Transparent.png\",\"width\":1999,\"height\":666,\"caption\":\"CIARB Conference\"},\"image\":{\"@id\":\"https:\\\/\\\/ciarbnigeria.org\\\/conference\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eferoghene Cherish Hunder - CIARB Conference","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciarbnigeria.org\/conference\/associate\/eferoghene-cherish-hunder\/","og_locale":"en_US","og_type":"article","og_title":"Eferoghene Cherish Hunder - CIARB Conference","og_description":"hunderefe@gmail.com","og_url":"https:\/\/ciarbnigeria.org\/conference\/associate\/eferoghene-cherish-hunder\/","og_site_name":"CIARB Conference","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciarbnigeria.org\/conference\/associate\/eferoghene-cherish-hunder\/","url":"https:\/\/ciarbnigeria.org\/conference\/associate\/eferoghene-cherish-hunder\/","name":"Eferoghene Cherish Hunder - CIARB Conference","isPartOf":{"@id":"https:\/\/ciarbnigeria.org\/conference\/#website"},"datePublished":"2026-05-02T09:23:07+00:00","breadcrumb":{"@id":"https:\/\/ciarbnigeria.org\/conference\/associate\/eferoghene-cherish-hunder\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciarbnigeria.org\/conference\/associate\/eferoghene-cherish-hunder\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ciarbnigeria.org\/conference\/associate\/eferoghene-cherish-hunder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ciarbnigeria.org\/conference\/"},{"@type":"ListItem","position":2,"name":"Associates","item":"https:\/\/ciarbnigeria.org\/conference\/associate\/"},{"@type":"ListItem","position":3,"name":"Eferoghene Cherish Hunder"}]},{"@type":"WebSite","@id":"https:\/\/ciarbnigeria.org\/conference\/#website","url":"https:\/\/ciarbnigeria.org\/conference\/","name":"CIARB Conference","description":"Annual Conference","publisher":{"@id":"https:\/\/ciarbnigeria.org\/conference\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciarbnigeria.org\/conference\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ciarbnigeria.org\/conference\/#organization","name":"CIARB Conference","url":"https:\/\/ciarbnigeria.org\/conference\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ciarbnigeria.org\/conference\/#\/schema\/logo\/image\/","url":"https:\/\/ciarbnigeria.org\/conference\/wp-content\/uploads\/2026\/04\/cropped-2026-Conference-logo-Transparent.png","contentUrl":"https:\/\/ciarbnigeria.org\/conference\/wp-content\/uploads\/2026\/04\/cropped-2026-Conference-logo-Transparent.png","width":1999,"height":666,"caption":"CIARB Conference"},"image":{"@id":"https:\/\/ciarbnigeria.org\/conference\/#\/schema\/logo\/image\/"}}]}},"ptb_metabox":[],"ptb_taxonomy":[],"ptb_featured_image":null,"_links":{"self":[{"href":"https:\/\/ciarbnigeria.org\/conference\/wp-json\/wp\/v2\/associate\/5854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciarbnigeria.org\/conference\/wp-json\/wp\/v2\/associate"}],"about":[{"href":"https:\/\/ciarbnigeria.org\/conference\/wp-json\/wp\/v2\/types\/associate"}],"wp:attachment":[{"href":"https:\/\/ciarbnigeria.org\/conference\/wp-json\/wp\/v2\/media?parent=5854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}